{"id":1832,"date":"2023-06-26T17:18:40","date_gmt":"2023-06-26T15:18:40","guid":{"rendered":"https:\/\/corlacortelaser.com\/services\/curvado\/"},"modified":"2023-06-29T09:53:38","modified_gmt":"2023-06-29T07:53:38","slug":"cintrage","status":"publish","type":"page","link":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/","title":{"rendered":"Cintrage"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section nav_skin=&#8221;light&#8221; section_show_on=&#8221;wtbx_hide_tablet_portrait,wtbx_hide_mobile_landscape,wtbx_hide_mobile_portrait&#8221;][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;mobile_portrait&#8220;:{&#8220;margin-right&#8220;:&#8220;20&#8220;,&#8220;margin-left&#8220;:&#8220;20&#8220;},&#8220;mobile_landscape&#8220;:{&#8220;margin-right&#8220;:&#8220;20&#8220;,&#8220;margin-left&#8220;:&#8220;20&#8220;},&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;60&#8220;,&#8220;padding-right&#8220;:&#8220;22%&#8220;,&#8220;padding-left&#8220;:&#8220;22%&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/3&#8243; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fdecoupe-laser-industrielle%2F|title:D%C3%A9coupe%20laser%20industrielle&#8221; el_class=&#8221;servicio2&#8243;][vc_service style=&#8221;left&#8221; heading=&#8221;D\u00e9coupe laser&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Corte-laser&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/3&#8243; css_animation=&#8221;&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fpliage%2F|title:Pliage&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; el_class=&#8221;servicio2&#8243;][vc_service style=&#8221;left&#8221; heading=&#8221;Pliage&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Plegadora&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][vc_column el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/3&#8243; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;Main accent color&#8220;,&#8220;color&#8220;:&#8220;#ec8828&#8220;}}&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Cintrage&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Curvado&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;mobile_portrait&#8220;:{&#8220;margin-right&#8220;:&#8220;20&#8220;,&#8220;margin-left&#8220;:&#8220;20&#8220;},&#8220;mobile_landscape&#8220;:{&#8220;margin-right&#8220;:&#8220;20&#8220;,&#8220;margin-left&#8220;:&#8220;20&#8220;},&#8220;desktop&#8220;:{&#8220;padding-right&#8220;:&#8220;12%&#8220;,&#8220;padding-left&#8220;:&#8220;12%&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/4&#8243; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; el_class=&#8221;servicio2&#8243; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fsoudure%2F|title:Soudure&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Soudure&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Soldadura&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/4&#8243; css_animation=&#8221;&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fusinage%2F|title:Usinage&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; el_class=&#8221;servicio2&#8243;][vc_service style=&#8221;left&#8221; heading=&#8221;Usinage&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Mecanizado&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/4&#8243; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fproduits-finis%2F|title:Produits%20finis&#8221; el_class=&#8221;servicio2&#8243;][vc_service style=&#8221;left&#8221; heading=&#8221;Produits finis&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Prod-term&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/4&#8243; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Ftraitements-superficiels-et-decoration%2F|title:Traitements%20superficiels%20et%20d%C3%A9coration&#8221; el_class=&#8221;servicio2&#8243;][vc_service style=&#8221;left&#8221; heading=&#8221;Traitements&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Tratamientos&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row row_width=&#8221;&#8221; max_width=&#8221;1000&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_2574427215217529&#8220;,&#8220;color&#8220;:&#8220;#f3f6fb&#8220;}}&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;margin-top&#8220;:&#8220;50&#8220;,&#8220;margin-right&#8220;:&#8220;50&#8220;,&#8220;margin-bottom&#8220;:&#8220;100&#8220;,&#8220;margin-left&#8220;:&#8220;50&#8220;,&#8220;padding-top&#8220;:&#8220;30&#8220;,&#8220;padding-right&#8220;:&#8220;30&#8220;,&#8220;padding-bottom&#8220;:&#8220;30&#8220;,&#8220;padding-left&#8220;:&#8220;30&#8220;}}&#8221;][vc_column css_animation=&#8221;&#8221;][vc_text_element css_animation=&#8221;&#8221;]Pour les travaux de cintrage, nous disposons d&#8217;une machine qui d\u00e9forme le mat\u00e9riau dans la forme souhait\u00e9e.[\/vc_text_element][vc_row_inner columns_placement=&#8221;middle&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221;][vc_column_inner el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;border-top&#8220;:0,&#8220;border-right&#8220;:2,&#8220;border-bottom&#8220;:0,&#8220;border-left&#8220;:0,&#8220;border-top-left-radius&#8220;:0,&#8220;border-top-right-radius&#8220;:0,&#8220;border-bottom-right-radius&#8220;:0,&#8220;border-bottom-left-radius&#8220;:0,&#8220;padding-top&#8220;:&#8220;15&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;15&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;,&#8220;border-style&#8220;:&#8220;solid&#8220;}}&#8221; width=&#8221;2\/3&#8243; css_animation=&#8221;&#8221; border_color=&#8221;{&#8220;id&#8220;:&#8220;custom_1919533005111031&#8220;,&#8220;color&#8220;:&#8220;#2d3543&#8220;}&#8221;][vc_service style=&#8221;left&#8221; bullet_type=&#8221;number&#8221; number=&#8221;1&#8243; bullet_typography=&#8221;{&#8220;variants&#8220;:&#8220;600&#8220;,&#8220;font_size&#8220;:&#8220;30px&#8220;}&#8221; heading=&#8221;MACHINE | Cintrage&#8221; css_animation=&#8221;&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221;]<\/p>\n<div id=\"uno\">\n<div class=\"left\">CINTRAGE AJIAL<\/div>\n<div class=\"right\">Largeur du cintraje: 2100 mm.<br \/>\nPuissance: 4 + 1,1 kw<\/div>\n<\/div>\n<p>[\/vc_service][\/vc_column_inner][vc_column_inner el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;15&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;15&#8220;,&#8220;padding-left&#8220;:&#8220;30&#8220;}}&#8221; width=&#8221;1\/3&#8243; css_animation=&#8221;&#8221;][vc_heading heading_text=&#8221;\u00c9paisseurs&#8221; heading_wrapper=&#8221;p&#8221; heading_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; heading_typography=&#8221;{&#8220;variants&#8220;:&#8220;400&#8220;,&#8220;font_size&#8220;:&#8220;24px&#8220;}&#8221; css_animation=&#8221;&#8221;][vc_list_item bullet_style=&#8221;icon&#8221; css_animation=&#8221;&#8221; bullet_icon=&#8221;{&#8220;font&#8220;:&#8220;scape-basic&#8220;,&#8220;icon&#8220;:&#8220;scape-basic-Check-1&#8220;}&#8221; bullet_color=&#8221;{&#8220;id&#8220;:&#8220;custom_7727897877526541&#8220;,&#8220;color&#8220;:&#8220;#ec8828&#8220;}&#8221;]Jusqu\u2019\u00e0 6 mm.[\/vc_list_item][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section nav_skin=&#8221;light&#8221; section_show_on=&#8221;wtbx_hide_on_normal_screen,wtbx_hide_tablet_landscape&#8221;][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;60&#8220;,&#8220;padding-right&#8220;:&#8220;20&#8220;,&#8220;padding-left&#8220;:&#8220;20&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fdecoupe-laser-industrielle%2F|title:D%C3%A9coupe%20laser%20industrielle&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;D\u00e9coupe laser&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;18px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Corte-laser&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;20&#8220;,&#8220;padding-left&#8220;:&#8220;20&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fpliage%2F|title:Pliage&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Pliage&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;18px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Plegadora&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;20&#8220;,&#8220;padding-left&#8220;:&#8220;20&#8220;}}&#8221;][vc_column el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;Main accent color&#8220;,&#8220;color&#8220;:&#8220;#ec8828&#8220;}}&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Cintrage&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;18px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Curvado&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;servicio-azul&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;20&#8220;,&#8220;padding-left&#8220;:&#8220;20&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fsoudure%2F|title:Soudure&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Soudure&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;18px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Soldadura&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;servicio-azul&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;20&#8220;,&#8220;padding-left&#8220;:&#8220;20&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fusinage%2F|title:Usinage&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Usinage&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;18px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Mecanizado&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;20&#8220;,&#8220;padding-left&#8220;:&#8220;20&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fproduits-finis%2F|title:Produits%20finis&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Produits finis&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;18px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Prod-term&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;20&#8220;,&#8220;padding-left&#8220;:&#8220;20&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Ftraitements-superficiels-et-decoration%2F|title:Traitements%20superficiels%20et%20d%C3%A9coration&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Traitements&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;18px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Tratamientos&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;servicio-azul&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row row_width=&#8221;&#8221; max_width=&#8221;1000&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_2574427215217529&#8220;,&#8220;color&#8220;:&#8220;#f3f6fb&#8220;}}&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;margin-top&#8220;:&#8220;50&#8220;,&#8220;padding-top&#8220;:&#8220;20&#8220;,&#8220;padding-right&#8220;:&#8220;20&#8220;,&#8220;padding-bottom&#8220;:&#8220;50&#8220;,&#8220;padding-left&#8220;:&#8220;20&#8220;}}&#8221;][vc_column css_animation=&#8221;&#8221;][vc_text_element css_animation=&#8221;&#8221;]Pour les travaux de cintrage, nous disposons d&#8217;une machine qui d\u00e9forme le mat\u00e9riau dans la forme souhait\u00e9e.[\/vc_text_element][vc_empty_space][vc_service style=&#8221;left&#8221; bullet_type=&#8221;number&#8221; number=&#8221;1&#8243; bullet_typography=&#8221;{&#8220;variants&#8220;:&#8220;600&#8220;,&#8220;font_size&#8220;:&#8220;30px&#8220;}&#8221; heading=&#8221;MACHINE | Cintrage&#8221; css_animation=&#8221;&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221;]CINTRAGE AJIAL<\/p>\n<p>Largeur du cintraje: 2100 mm.<br \/>\nPuissance: 4 + 1,1 kw[\/vc_service][vc_empty_space height=&#8221;40px&#8221;][vc_heading heading_text=&#8221;\u00c9paisseurs&#8221; heading_wrapper=&#8221;p&#8221; heading_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; heading_typography=&#8221;{&#8220;variants&#8220;:&#8220;400&#8220;,&#8220;font_size&#8220;:&#8220;24px&#8220;}&#8221; css_animation=&#8221;&#8221;][vc_empty_space height=&#8221;20px&#8221;][vc_list_item bullet_style=&#8221;icon&#8221; css_animation=&#8221;&#8221; bullet_icon=&#8221;{&#8220;font&#8220;:&#8220;scape-basic&#8220;,&#8220;icon&#8220;:&#8220;scape-basic-Check-1&#8220;}&#8221; bullet_color=&#8221;{&#8220;id&#8220;:&#8220;custom_7727897877526541&#8220;,&#8220;color&#8220;:&#8220;#ec8828&#8220;}&#8221;]Jusqu\u2019\u00e0 6 mm.[\/vc_list_item][vc_empty_space height=&#8221;10px&#8221;][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section nav_skin=&#8221;light&#8221; section_show_on=&#8221;wtbx_hide_tablet_portrait,wtbx_hide_mobile_landscape,wtbx_hide_mobile_portrait&#8221;][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;mobile_portrait&#8220;:{&#8220;margin-right&#8220;:&#8220;20&#8220;,&#8220;margin-left&#8220;:&#8220;20&#8220;},&#8220;mobile_landscape&#8220;:{&#8220;margin-right&#8220;:&#8220;20&#8220;,&#8220;margin-left&#8220;:&#8220;20&#8220;},&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;60&#8220;,&#8220;padding-right&#8220;:&#8220;22%&#8220;,&#8220;padding-left&#8220;:&#8220;22%&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/3&#8243; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fdecoupe-laser-industrielle%2F|title:D%C3%A9coupe%20laser%20industrielle&#8221; el_class=&#8221;servicio2&#8243;][vc_service style=&#8221;left&#8221; heading=&#8221;D\u00e9coupe laser&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Corte-laser&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/3&#8243; css_animation=&#8221;&#8221; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fpliage%2F|title:Pliage&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; el_class=&#8221;servicio2&#8243;][vc_service style=&#8221;left&#8221; heading=&#8221;Pliage&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Plegadora&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][vc_column el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/3&#8243; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;Main accent color&#8220;,&#8220;color&#8220;:&#8220;#ec8828&#8220;}}&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Cintrage&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Curvado&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][\/vc_row][vc_row gap=&#8221;20&#8243; nav_skin=&#8221;light&#8221; consent_include=&#8221;include&#8221; equal_height=&#8221;true&#8221; el_design=&#8221;{&#8220;mobile_portrait&#8220;:{&#8220;margin-right&#8220;:&#8220;20&#8220;,&#8220;margin-left&#8220;:&#8220;20&#8220;},&#8220;mobile_landscape&#8220;:{&#8220;margin-right&#8220;:&#8220;20&#8220;,&#8220;margin-left&#8220;:&#8220;20&#8220;},&#8220;desktop&#8220;:{&#8220;padding-right&#8220;:&#8220;12%&#8220;,&#8220;padding-left&#8220;:&#8220;12%&#8220;}}&#8221;][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; width=&#8221;1\/4&#8243; css_animation=&#8221;&#8221; custom_bg_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_0115190616506819&#8220;,&#8220;color&#8220;:&#8220;#2b3443&#8220;}}&#8221; el_class=&#8221;servicio2&#8243; link=&#8221;url:https%3A%2F%2Fcorlacortelaser.com%2Ffr%2Fservices%2Fsoudure%2F|title:Soudure&#8221;][vc_service style=&#8221;left&#8221; heading=&#8221;Soudure&#8221; heading_typography=&#8221;{&#8220;transform&#8220;:&#8220;uppercase&#8220;,&#8220;font_size&#8220;:&#8220;15px&#8220;}&#8221; css_animation=&#8221;&#8221; icon=&#8221;{&#8220;font&#8220;:&#8220;corla-2023-v1.0&#8220;,&#8220;icon&#8220;:&#8220;icon-Soldadura&#8220;}&#8221; bullet_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; title_color=&#8221;{&#8220;solid&#8220;:{&#8220;id&#8220;:&#8220;custom_1141411115464664&#8220;,&#8220;color&#8220;:&#8220;#ffffff&#8220;}}&#8221; el_class=&#8221;icono-recuadro&#8221;][\/vc_service][\/vc_column][vc_column column_link=&#8221;yes&#8221; el_design=&#8221;{&#8220;desktop&#8220;:{&#8220;padding-top&#8220;:&#8220;5&#8220;,&#8220;padding-right&#8220;:&#8220;15&#8220;,&#8220;padding-bottom&#8220;:&#8220;2&#8220;,&#8220;padding-left&#8220;:&#8220;15&#8220;}}&#8221; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1809,"parent":1494,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1832","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servicio de curvado de piezas para la industria<\/title>\n<meta name=\"description\" content=\"Para realizar trabajos de curvado contamos con una m\u00e1quina que deforma el material hasta adquirir la forma deseada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicio de curvado de piezas para la industria\" \/>\n<meta property=\"og:description\" content=\"Para realizar trabajos de curvado contamos con una m\u00e1quina que deforma el material hasta adquirir la forma deseada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/\" \/>\n<meta property=\"og:site_name\" content=\"CORLA\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-29T07:53:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corlacortelaser.com\/wp-content\/uploads\/hero-curvado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/cintrage\\\/\",\"url\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/cintrage\\\/\",\"name\":\"Servicio de curvado de piezas para la industria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/cintrage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/cintrage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corlacortelaser.com\\\/wp-content\\\/uploads\\\/hero-curvado.jpg\",\"datePublished\":\"2023-06-26T15:18:40+00:00\",\"dateModified\":\"2023-06-29T07:53:38+00:00\",\"description\":\"Para realizar trabajos de curvado contamos con una m\u00e1quina que deforma el material hasta adquirir la forma deseada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/cintrage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/cintrage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/cintrage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corlacortelaser.com\\\/wp-content\\\/uploads\\\/hero-curvado.jpg\",\"contentUrl\":\"https:\\\/\\\/corlacortelaser.com\\\/wp-content\\\/uploads\\\/hero-curvado.jpg\",\"width\":1920,\"height\":600,\"caption\":\"Servicio de Curvado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/cintrage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/corlacortelaser.com\\\/fr\\\/services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cintrage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/#website\",\"url\":\"https:\\\/\\\/corlacortelaser.com\\\/\",\"name\":\"CORLA\",\"description\":\"m\u00e1s que Corte L\u00e1ser Industrial\",\"publisher\":{\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corlacortelaser.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/#organization\",\"name\":\"CORLA\",\"url\":\"https:\\\/\\\/corlacortelaser.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corlacortelaser.com\\\/wp-content\\\/uploads\\\/corla.png\",\"contentUrl\":\"https:\\\/\\\/corlacortelaser.com\\\/wp-content\\\/uploads\\\/corla.png\",\"width\":700,\"height\":700,\"caption\":\"CORLA\"},\"image\":{\"@id\":\"https:\\\/\\\/corlacortelaser.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/corlacortelaser\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servicio de curvado de piezas para la industria","description":"Para realizar trabajos de curvado contamos con una m\u00e1quina que deforma el material hasta adquirir la forma deseada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/","og_locale":"fr_FR","og_type":"article","og_title":"Servicio de curvado de piezas para la industria","og_description":"Para realizar trabajos de curvado contamos con una m\u00e1quina que deforma el material hasta adquirir la forma deseada.","og_url":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/","og_site_name":"CORLA","article_modified_time":"2023-06-29T07:53:38+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/corlacortelaser.com\/wp-content\/uploads\/hero-curvado.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/","url":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/","name":"Servicio de curvado de piezas para la industria","isPartOf":{"@id":"https:\/\/corlacortelaser.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/#primaryimage"},"image":{"@id":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/#primaryimage"},"thumbnailUrl":"https:\/\/corlacortelaser.com\/wp-content\/uploads\/hero-curvado.jpg","datePublished":"2023-06-26T15:18:40+00:00","dateModified":"2023-06-29T07:53:38+00:00","description":"Para realizar trabajos de curvado contamos con una m\u00e1quina que deforma el material hasta adquirir la forma deseada.","breadcrumb":{"@id":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/#primaryimage","url":"https:\/\/corlacortelaser.com\/wp-content\/uploads\/hero-curvado.jpg","contentUrl":"https:\/\/corlacortelaser.com\/wp-content\/uploads\/hero-curvado.jpg","width":1920,"height":600,"caption":"Servicio de Curvado"},{"@type":"BreadcrumbList","@id":"https:\/\/corlacortelaser.com\/fr\/services\/cintrage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/corlacortelaser.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/corlacortelaser.com\/fr\/services\/"},{"@type":"ListItem","position":3,"name":"Cintrage"}]},{"@type":"WebSite","@id":"https:\/\/corlacortelaser.com\/#website","url":"https:\/\/corlacortelaser.com\/","name":"CORLA","description":"m\u00e1s que Corte L\u00e1ser Industrial","publisher":{"@id":"https:\/\/corlacortelaser.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corlacortelaser.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/corlacortelaser.com\/#organization","name":"CORLA","url":"https:\/\/corlacortelaser.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/corlacortelaser.com\/#\/schema\/logo\/image\/","url":"https:\/\/corlacortelaser.com\/wp-content\/uploads\/corla.png","contentUrl":"https:\/\/corlacortelaser.com\/wp-content\/uploads\/corla.png","width":700,"height":700,"caption":"CORLA"},"image":{"@id":"https:\/\/corlacortelaser.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/in\/corlacortelaser\/"]}]}},"_links":{"self":[{"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/pages\/1832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/comments?post=1832"}],"version-history":[{"count":7,"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/pages\/1832\/revisions"}],"predecessor-version":[{"id":1950,"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/pages\/1832\/revisions\/1950"}],"up":[{"embeddable":true,"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/pages\/1494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/media\/1809"}],"wp:attachment":[{"href":"https:\/\/corlacortelaser.com\/fr\/wp-json\/wp\/v2\/media?parent=1832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}